{"id":6838,"date":"2025-02-07T12:19:58","date_gmt":"2025-02-07T15:19:58","guid":{"rendered":"https:\/\/isfd19-bue.infd.edu.ar\/sitio\/?p=6838"},"modified":"2025-02-07T12:20:00","modified_gmt":"2025-02-07T15:20:00","slug":"inicio-de-actividades-institucionales-2025","status":"publish","type":"post","link":"https:\/\/isfd19-bue.infd.edu.ar\/sitio\/inicio-de-actividades-institucionales-2025\/","title":{"rendered":"INICIO DE ACTIVIDADES INSTITUCIONALES 2025"},"content":{"rendered":"\n<p>Querida <strong>Comunidad Educativa del ISFD 19<\/strong>:<\/p>\n\n\n\n<p>Esperamos que hayan pasado un descansado y energizante receso vacacional!! Queremos informarles que la totalidad del personal del Instituto (en todas las sedes y los tres turnos) se reintegrar\u00e1 a sus funciones a partir del <strong>MARTES 11\/2\/2025<\/strong>.<br>La informaci\u00f3n sobre la organizaci\u00f3n para el inicio de este ciclo lectivo 2025 ser\u00e1 compartida como habitualmente, por medio de la p\u00e1gina de NOVEDADES de la Plataforma Institucional y replicada en el grupo de difusi\u00f3n de Secretar\u00eda y el canal de WhatsApp. El equipo docente tambi\u00e9n podr\u00eda recibir informaci\u00f3n espec\u00edfica de cada carrera por medio de los correos de las respectivas Jefaturas de \u00c1rea.<br>Vamos calentando motores\u2026 Nos encontramos en unos d\u00edas!! Que tengamos un muy buen a\u00f1o\u2026<\/p>\n\n\n\n<p class=\"has-text-align-center\"><strong>Equipo Directivo y de Conducci\u00f3n<\/strong><br>ISFD 19 &#8211; Mar del Plata\/Bat\u00e1n<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Querida Comunidad Educativa del ISFD 19: Esperamos que hayan pasado un descansado y energizante receso vacacional!! Queremos informarles que la totalidad del personal del Instituto (en todas las sedes y los tres turnos) se reintegrar\u00e1 a sus funciones a partir del MARTES 11\/2\/2025.La informaci\u00f3n sobre la organizaci\u00f3n para el inicio de este ciclo lectivo 2025 &#8230; <a title=\"INICIO DE ACTIVIDADES INSTITUCIONALES 2025\" class=\"read-more\" href=\"https:\/\/isfd19-bue.infd.edu.ar\/sitio\/inicio-de-actividades-institucionales-2025\/\" aria-label=\"More on INICIO DE ACTIVIDADES INSTITUCIONALES 2025\">[+]<\/a><\/p>\n","protected":false},"author":594,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/isfd19-bue.infd.edu.ar\/sitio\/wp-json\/wp\/v2\/posts\/6838"}],"collection":[{"href":"https:\/\/isfd19-bue.infd.edu.ar\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/isfd19-bue.infd.edu.ar\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/isfd19-bue.infd.edu.ar\/sitio\/wp-json\/wp\/v2\/users\/594"}],"replies":[{"embeddable":true,"href":"https:\/\/isfd19-bue.infd.edu.ar\/sitio\/wp-json\/wp\/v2\/comments?post=6838"}],"version-history":[{"count":1,"href":"https:\/\/isfd19-bue.infd.edu.ar\/sitio\/wp-json\/wp\/v2\/posts\/6838\/revisions"}],"predecessor-version":[{"id":6839,"href":"https:\/\/isfd19-bue.infd.edu.ar\/sitio\/wp-json\/wp\/v2\/posts\/6838\/revisions\/6839"}],"wp:attachment":[{"href":"https:\/\/isfd19-bue.infd.edu.ar\/sitio\/wp-json\/wp\/v2\/media?parent=6838"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/isfd19-bue.infd.edu.ar\/sitio\/wp-json\/wp\/v2\/categories?post=6838"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/isfd19-bue.infd.edu.ar\/sitio\/wp-json\/wp\/v2\/tags?post=6838"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}