{"id":6310,"date":"2023-09-15T10:59:18","date_gmt":"2023-09-15T13:59:18","guid":{"rendered":"https:\/\/isfd19-bue.infd.edu.ar\/sitio\/?p=6310"},"modified":"2023-09-15T10:59:20","modified_gmt":"2023-09-15T13:59:20","slug":"egresados-2022-2023","status":"publish","type":"post","link":"https:\/\/isfd19-bue.infd.edu.ar\/sitio\/egresados-2022-2023\/","title":{"rendered":"Egresados 2022 &#8211; 2023."},"content":{"rendered":"\n<p>Se comunica por este medio que el pr\u00f3ximo Mi\u00e9rcoles 20\/9 a las 19 hs. en forma virtual, haremos una reuni\u00f3n informativa dada la proximidad del Acto de Colaci\u00f3n. La misma es para todos aquellos egresados que hayan terminado su carrera entre noviembre\/diciembre de 2022 y agosto de 2023.<\/p>\n\n\n\n<p>Desde el departamento de alumnos, a la brevedad, se les estar\u00e1 enviando v\u00eda mail, el enlace para poder unirse.<\/p>\n\n\n\n<p>Se les pide adem\u00e1s, por favor, que respondan al correo que se les remiti\u00f3, por la asistencia o no al acto, dato muy importante para la organizaci\u00f3n.  <\/p>\n\n\n\n<p>Seguimos en contacto!<\/p>\n\n\n\n<p>En nombre del Equipo Directivo, los saludo con un gran cari\u00f1o!<\/p>\n\n\n\n<p>Prof. del Barrio Marcela A.<\/p>\n\n\n\n<p>Viced. ISFD n\u00b0 19. <\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se comunica por este medio que el pr\u00f3ximo Mi\u00e9rcoles 20\/9 a las 19 hs. en forma virtual, haremos una reuni\u00f3n informativa dada la proximidad del Acto de Colaci\u00f3n. La misma es para todos aquellos egresados que hayan terminado su carrera entre noviembre\/diciembre de 2022 y agosto de 2023. Desde el departamento de alumnos, a la &#8230; <a title=\"Egresados 2022 &#8211; 2023.\" class=\"read-more\" href=\"https:\/\/isfd19-bue.infd.edu.ar\/sitio\/egresados-2022-2023\/\" aria-label=\"More on Egresados 2022 &#8211; 2023.\">[+]<\/a><\/p>\n","protected":false},"author":6290,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/isfd19-bue.infd.edu.ar\/sitio\/wp-json\/wp\/v2\/posts\/6310"}],"collection":[{"href":"https:\/\/isfd19-bue.infd.edu.ar\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/isfd19-bue.infd.edu.ar\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/isfd19-bue.infd.edu.ar\/sitio\/wp-json\/wp\/v2\/users\/6290"}],"replies":[{"embeddable":true,"href":"https:\/\/isfd19-bue.infd.edu.ar\/sitio\/wp-json\/wp\/v2\/comments?post=6310"}],"version-history":[{"count":1,"href":"https:\/\/isfd19-bue.infd.edu.ar\/sitio\/wp-json\/wp\/v2\/posts\/6310\/revisions"}],"predecessor-version":[{"id":6311,"href":"https:\/\/isfd19-bue.infd.edu.ar\/sitio\/wp-json\/wp\/v2\/posts\/6310\/revisions\/6311"}],"wp:attachment":[{"href":"https:\/\/isfd19-bue.infd.edu.ar\/sitio\/wp-json\/wp\/v2\/media?parent=6310"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/isfd19-bue.infd.edu.ar\/sitio\/wp-json\/wp\/v2\/categories?post=6310"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/isfd19-bue.infd.edu.ar\/sitio\/wp-json\/wp\/v2\/tags?post=6310"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}